{"id":105,"count":1,"description":"","link":"https:\/\/mexela.com\/blog\/tag\/proxy-data-collection\/","name":"proxy data collection","slug":"proxy-data-collection","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/mexela.com\/blog\/wp-json\/wp\/v2\/tags\/105"}],"collection":[{"href":"https:\/\/mexela.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mexela.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mexela.com\/blog\/wp-json\/wp\/v2\/posts?tags=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}